{"id":4039,"date":"2019-10-31T08:50:56","date_gmt":"2019-10-31T07:50:56","guid":{"rendered":"http:\/\/dhitelfon.com\/?p=4039"},"modified":"2019-10-31T08:50:56","modified_gmt":"2019-10-31T07:50:56","slug":"te-explicamos-que-es-apple-carplay-y-como-funciona","status":"publish","type":"post","link":"https:\/\/dhitelfon.com\/en\/te-explicamos-que-es-apple-carplay-y-como-funciona\/","title":{"rendered":"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona"},"content":{"rendered":"<p>\u00bfSabes qu\u00e9 es Apple CarPlay y c\u00f3mo funciona ? Hasta donde sabemos,\u00a0<a href=\"https:\/\/es.digitaltrends.com\/apple\/apple-vehiculos-autonomos\/\">Apple nunca dise\u00f1ar\u00e1<\/a>\u00a0sus propios autom\u00f3viles \u201cdesde cero\u201d, pero tampoco quieren dejar de ser un jugador clave en la industria automotriz. Lanzado en 2014, despu\u00e9s de un largo proceso de desarrollo, el software\u00a0<a href=\"https:\/\/www.apple.com\/mx\/ios\/carplay\/\">CarPlay<\/a>\u00a0se superpone al sistema de informaci\u00f3n y entretenimiento que viene de f\u00e1brica en algunos autom\u00f3viles, llevando as\u00ed los datos de est\u00e1n en tu iPhone a la pantalla central de tu carro.<\/p>\n<figure id=\"attachment_698168\" class=\"wp-caption aligncenter\"><a class=\"wp-image-698168 size-large-wrap\" href=\"https:\/\/icdn6.digitaltrends.com\/image\/digitaltrends_es\/switzerland-auto-show-us-internet-apple-computers-720x480.jpg\"><img decoding=\"async\" class=\"wp-image-698168 size-large dt-lazy-load dt-lazy-loaded\" src=\"https:\/\/icdn8.digitaltrends.com\/image\/digitaltrends_es\/switzerland-auto-show-us-internet-apple-computers-768x768.jpg\" alt=\"qu\u00e9 es Apple CarPlay\" data-dt-lazy-src=\"https:\/\/icdn8.digitaltrends.com\/image\/digitaltrends_es\/switzerland-auto-show-us-internet-apple-computers-720x720.jpg\" \/><\/a><figcaption id=\"caption-attachment-698168\" class=\"wp-caption-text\">Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona<\/figcaption><\/figure>\n<p>CarPlay hace que conducir sea m\u00e1s seguro, al reducir las distracciones (o, al menos, eso aseguran en\u00a0<a href=\"https:\/\/newsroom.aaa.com\/2018\/06\/apple-google-safer-vehicle-infotainment-technology\/\" target=\"_blank\" rel=\"noopener noreferrer\">Apple y la AAA<\/a>), y es m\u00e1s f\u00e1cil de usar que muchos sistemas de\u00a0<em>infotainment<\/em>\u00a0OEM. Esto se debe a que los automovilistas pueden acceder a una amplia variedad de funciones sin tener que tocar su dispositivo m\u00f3vil ni apartar su vista de la carretera.<\/p>\n<p><em>\u00bfNo eres un usuario de iPhone? Entonces te interesar\u00e1 saber\u00a0<a href=\"https:\/\/es.digitaltrends.com\/autos\/como-funciona-android-auto\/\">todo lo relativo a Android Auto<\/a><\/em>.<\/p>\n<h2><strong>\u00bfQu\u00e9 puede hacer Apple CarPlay?<\/strong><\/h2>\n<p>Apple CarPlay realiza muchas de las mismas funciones que un iPhone. Los automovilistas pueden usar el software para obtener indicaciones giro a giro, realizar llamadas, enviar y recibir mensajes de texto, y escuchar m\u00fasica o podcasts. Las caracter\u00edsticas se muestran en una interfaz f\u00e1cil de usar, con unos iconos grandes que ser\u00e1n reconocidos al momento por los usuarios de iPhone.<\/p>\n<div id=\"dt-carousel-5dba90efd162b\" class=\"m-carousel is-first h-carousel\">\n<div class=\"m-carousel--wrap h-carousel-wrap\">\n<div class=\"m-carousel--controls h-controls\"><\/div>\n<div class=\"m-carousel--slides h-slides\">\n<div class=\"m-carousel--slide m-carousel--slide_image h-slide is-current is-loaded\" data-options-key=\"\" data-slug=\"1\" data-type=\"image\">\n<figure class=\"m-carousel--content\"><img decoding=\"async\" class=\"m-carousel--image dt-lazy-no\" src=\"https:\/\/icdn2.digitaltrends.com\/image\/digitaltrends_es\/new-carplay-5-640x640.jpg\" srcset=\"https:\/\/icdn2.digitaltrends.com\/image\/digitaltrends_es\/new-carplay-5-700x467-c.jpg\" alt=\"\" \/><\/figure>\n<\/div>\n<div class=\"m-carousel--slide m-carousel--slide_image h-slide is-next is-loaded\" data-options-key=\"\" data-slug=\"2\" data-type=\"image\">\n<figure class=\"m-carousel--content\"><img decoding=\"async\" class=\"m-carousel--image dt-lazy-no\" src=\"https:\/\/icdn3.digitaltrends.com\/image\/digitaltrends_es\/new-carplay-3-640x640.jpg\" srcset=\"https:\/\/icdn3.digitaltrends.com\/image\/digitaltrends_es\/new-carplay-3-700x467-c.jpg\" alt=\"\" \/><\/figure>\n<\/div>\n<div class=\"m-carousel--slide m-carousel--slide_image is-pending h-slide is-prev\" data-options-key=\"\" data-slug=\"4\" data-type=\"image\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Se puede acceder a buena parte de las caracter\u00edsticas de CarPlay usando\u00a0<a href=\"https:\/\/www.apple.com\/ios\/siri\/\">Siri, el asistente digital de Apple<\/a>. Por ejemplo, el conductor puede decir \u201cllamar a Alex K\u201d, \u201cdame indicaciones para llegar al Caf\u00e9 R\u00edo\u201d o \u201cescuchar a Dropkick Murphys\u201d, y Siri obedecer\u00e1. Un automovilista cuyo carro no est\u00e9 equipado con la tecnolog\u00eda de reconocimiento de voz, igualmente podr\u00e1 navegar por el software utilizando la pantalla t\u00e1ctil del tablero, o las diferentes perillas y botones que normalmente se encuentran en el volante y la consola central. Al igual que sucede con su competencia Android Auto, la pantalla del iPhone se bloquea cuando CarPlay est\u00e1 activo<\/p>\n<p>Una peque\u00f1a selecci\u00f3n de aplicaciones de terceros son compatibles y est\u00e1n optimizadas para CarPlay. Los primeros en adoptarlo incluyeron a iHeartRadio, Spotify, Pandora y Stitcher. Poco despu\u00e9s, entr\u00f3 en el juego Tidal, quien anunci\u00f3 en diciembre que finalmente se unir\u00eda a la fiesta. Ahora, la gente puede escuchar los \u00e1lbumes de Jay Z o Beyonce reci\u00e9n salidos directamente en sus autos.<\/p>\n<figure class=\"aligncenter\"><a class=\"wp-image-677079 size-large-wrap\" href=\"https:\/\/icdn8.digitaltrends.com\/image\/digitaltrends_es\/new-carplay-1-720x480.jpg\"><img decoding=\"async\" class=\"size-large wp-image-677079 dt-lazy-load dt-lazy-loaded\" src=\"https:\/\/icdn4.digitaltrends.com\/image\/digitaltrends_es\/new-carplay-1-768x768.jpg\" alt=\"\" data-dt-lazy-src=\"https:\/\/icdn4.digitaltrends.com\/image\/digitaltrends_es\/new-carplay-1-720x720.jpg\" \/><\/a><\/figure>\n<p>Pero ojo, que la configuraci\u00f3n misma del veh\u00edculo no es parte de CarPlay, por lo que el conductor tendr\u00e1 que salirse de la aplicaci\u00f3n para ajustar (por ejemplo) el control de temperatura, buscar estaciones de radio o seleccionar un modo de conducci\u00f3n diferente. Si bien Google ha ayudado a los fabricantes de autom\u00f3viles a desarrollar sistemas de informaci\u00f3n y entretenimiento \u2013 especialmente a Volvo\u2013, nadie ha firmado una asociaci\u00f3n similar con Apple. Al menos no todav\u00eda.<\/p>\n<h2><strong>\u00bfQu\u00e9 tel\u00e9fonos son compatibles con Apple CarPlay<\/strong><\/h2>\n<p>Los conductores que quieren el sistema operativo de Apple en su panel necesitar\u00e1n \u2014onbiamente\u2014 un iPhone compatible. Todos los modelos iPhone desde el 5 son compatibles con CarPlay, aunque el dispositivo necesitar\u00e1 ejecutar el iOS 7.1 o posterior para que la aplicaci\u00f3n funcione.<\/p>\n<p>Algunos autos\u00a0<a href=\"https:\/\/support.apple.com\/es-mx\/HT205634\">tambi\u00e9n admiten CarPlay inal\u00e1mbrico<\/a>. En los que no, el iPhone necesitar\u00e1 estar f\u00edsicamente conectado al autom\u00f3vil a trav\u00e9s de un cable Lightning-a-USB certificado.<\/p>\n<h2><strong>\u00bfQu\u00e9 carros son compatible con Apple CarPlay?<\/strong><\/h2>\n<p>Una amplia variedad de modelos de todo el espectro automotriz\u00a0<a href=\"https:\/\/www.apple.com\/ios\/carplay\/available-models\/\" target=\"_blank\" rel=\"noopener noreferrer\">es compatible con Apple CarPlay<\/a>. Esta compatibilidad va desde modelos relativamente b\u00e1sicos como el Chevrolet Spark, hasta superdeportivos de gama alta como el\u00a0<a href=\"https:\/\/es.digitaltrends.com\/autos\/manejando-lamborghini-aventador-s\/\">Lamborghini Aventador S<\/a>. Volvo, Honda, Chevrolet, Ford y Porsche est\u00e1n\u00a0<a href=\"https:\/\/www.apple.com\/ios\/carplay\/available-models\/\">entre las docenas de marcas<\/a>\u00a0que ofrecen compatibilidad con CarPlay. Ten en cuenta que algunas compa\u00f1\u00edas cobran un extra por incluir el CarPlay en sus modelos, mientras que otras lo ponen como equipamiento est\u00e1ndar.<\/p>\n<div id=\"dtads-leaderboard-0l6ku6zcyn5b\" class=\"dtads-slot dtads-slot-leaderboard dtads-desktop callout solid dtads-is-rendered\" data-google-query-id=\"CN2DnYKBxuUCFUzGuwgdlJ8PgA\"><\/div>\n<figure id=\"attachment_698167\" class=\"wp-caption aligncenter\"><a class=\"wp-image-698167 size-large-wrap\" href=\"https:\/\/icdn7.digitaltrends.com\/image\/digitaltrends_es\/que-es-apple-carplay-01-720x480.jpg\"><img decoding=\"async\" class=\"size-large wp-image-698167 dt-lazy-load dt-lazy-loaded\" src=\"https:\/\/icdn9.digitaltrends.com\/image\/digitaltrends_es\/que-es-apple-carplay-01-768x768.jpg\" alt=\"que es apple carplay 01\" data-dt-lazy-src=\"https:\/\/icdn9.digitaltrends.com\/image\/digitaltrends_es\/que-es-apple-carplay-01-720x720.jpg\" \/><\/a><\/figure>\n<figure class=\"wp-caption aligncenter\">Te explicamos\u00a0<a class=\"wp-image-698167 size-large-wrap\" href=\"https:\/\/icdn7.digitaltrends.com\/image\/digitaltrends_es\/que-es-apple-carplay-01-720x480.jpg\">qu\u00e9 es Apple CarPlay y c\u00f3mo funciona<br \/>\n<\/a><\/figure>\n<p>Toyota pas\u00f3 a\u00f1os resisti\u00e9ndose a CarPlay y al software rival de Google, Android Auto, debido a su celo en temas de seguridad y privacidad. La firma japonesa recientemente cambi\u00f3 de opini\u00f3n y comenz\u00f3 a ofrecer CarPlay en algunos de sus modelos, incluidos el RAV4 2019, el\u00a0<a href=\"https:\/\/es.digitaltrends.com\/autos\/nuevo-toyota-corolla-hatchback-2019\/\">Corolla Hatch 2019<\/a>\u00a0y el\u00a0<a href=\"https:\/\/es.digitaltrends.com\/autos\/toyota-avalon-2019-nuevo-diseno\/\">Avalon 2019<\/a>. Lexus, propiedad de Toyota, tambi\u00e9n comenz\u00f3 a implementar el software en algunos de sus autos, como el ES y el RX. Es seguro apostar que otros modelos se sumar\u00e1n a esta lista.<\/p>\n<p>Dicho lo anterior: si est\u00e1s considerando comprarte un auto nuevo, no te ser\u00e1 dif\u00edcil encontrar uno equipado con Apple CarPlay. Hay cientos, sobre todo si vives en Am\u00e9rica del Norte. La historia es diferente en Europa, donde los fabricantes han sido m\u00e1s lentos para adoptar la tecnolog\u00eda.<\/p>\n<p>La lista de autos usados ??compatibles con CarPlay se est\u00e1 alargando cada a\u00f1o. Sin embargo, si manejas un\u00a0<a href=\"https:\/\/www.hagerty.com\/articles-videos\/articles\/2019\/04\/22\/second-generation-m5-underappreciated-bargain\">BMW de la d\u00e9cada de 1980<\/a>\u00a0o algo a\u00fan\u00a0<a href=\"https:\/\/ranwhenparked.net\/2014\/05\/01\/a-quick-drive-in-a-1977-volkswagen-polo-l-mk1\/\">m\u00e1s antiguo<\/a>, ten en cuenta que\u00a0<a href=\"https:\/\/www.alpine-usa.com\/\">Alpine<\/a>, Kenwood, Pioneer y Sony venden sistemas de posventa compatibles con CarPlay que brindan una integraci\u00f3n de tel\u00e9fonos inteligentes de vanguardia al mundo de los autos cl\u00e1sicos.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfSabes qu\u00e9 es Apple CarPlay y c\u00f3mo funciona ? Hasta donde sabemos,\u00a0Apple nunca dise\u00f1ar\u00e1\u00a0sus propios autom\u00f3viles \u201cdesde cero\u201d, pero tampoco quieren dejar de ser un jugador clave en la industria automotriz. Lanzado en 2014, despu\u00e9s de un largo proceso de desarrollo, el software\u00a0CarPlay\u00a0se superpone al sistema de informaci\u00f3n y entretenimiento que viene de f\u00e1brica en [&hellip;]<\/p>","protected":false},"author":2,"featured_media":3941,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[52],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona - DHITELfon<\/title>\n<meta name=\"description\" content=\"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dhitelfon.com\/en\/te-explicamos-que-es-apple-carplay-y-como-funciona\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona - DHITELfon\" \/>\n<meta property=\"og:description\" content=\"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dhitelfon.com\/en\/te-explicamos-que-es-apple-carplay-y-como-funciona\/\" \/>\n<meta property=\"og:site_name\" content=\"DHITELfon\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-31T07:50:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhitelfon.com\/wp-content\/uploads\/2019\/05\/CAR-PLAY.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1633\" \/>\n\t<meta property=\"og:image:height\" content=\"941\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dhitelfon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dhitelfon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/\",\"url\":\"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/\",\"name\":\"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona - DHITELfon\",\"isPartOf\":{\"@id\":\"https:\/\/dhitelfon.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dhitelfon.com\/wp-content\/uploads\/2019\/05\/CAR-PLAY.jpg\",\"datePublished\":\"2019-10-31T07:50:56+00:00\",\"dateModified\":\"2019-10-31T07:50:56+00:00\",\"author\":{\"@id\":\"https:\/\/dhitelfon.com\/#\/schema\/person\/a3af0a1b32d06c6e8f14a46114ea5509\"},\"description\":\"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona\",\"breadcrumb\":{\"@id\":\"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#primaryimage\",\"url\":\"https:\/\/dhitelfon.com\/wp-content\/uploads\/2019\/05\/CAR-PLAY.jpg\",\"contentUrl\":\"https:\/\/dhitelfon.com\/wp-content\/uploads\/2019\/05\/CAR-PLAY.jpg\",\"width\":1633,\"height\":941,\"caption\":\"Con este pincho USB se puede usar CarPlay en casi cualquier coche\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/dhitelfon.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dhitelfon.com\/#website\",\"url\":\"https:\/\/dhitelfon.com\/\",\"name\":\"DHITELfon\",\"description\":\"20 a\u00f1os de experiencia en el sector de comunicaciones, car audio, sistemas de seguridad para el autom\u00f3vil, sistemas de entretenimiento para el veh\u00edculo como tambi\u00e9n mayoristas de las mejores marcas. Centro instalador con taller propio\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dhitelfon.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dhitelfon.com\/#\/schema\/person\/a3af0a1b32d06c6e8f14a46114ea5509\",\"name\":\"Dhitelfon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/dhitelfon.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0107775308edc8de8d97206ddaa5c1bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0107775308edc8de8d97206ddaa5c1bb?s=96&d=mm&r=g\",\"caption\":\"Dhitelfon\"},\"sameAs\":[\"http:\/\/dhitelfon.com\"],\"url\":\"https:\/\/dhitelfon.com\/en\/author\/dhitelfon\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona - DHITELfon","description":"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dhitelfon.com\/en\/te-explicamos-que-es-apple-carplay-y-como-funciona\/","og_locale":"en_GB","og_type":"article","og_title":"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona - DHITELfon","og_description":"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona","og_url":"https:\/\/dhitelfon.com\/en\/te-explicamos-que-es-apple-carplay-y-como-funciona\/","og_site_name":"DHITELfon","article_published_time":"2019-10-31T07:50:56+00:00","og_image":[{"width":1633,"height":941,"url":"https:\/\/dhitelfon.com\/wp-content\/uploads\/2019\/05\/CAR-PLAY.jpg","type":"image\/jpeg"}],"author":"Dhitelfon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dhitelfon","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/","url":"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/","name":"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona - DHITELfon","isPartOf":{"@id":"https:\/\/dhitelfon.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#primaryimage"},"image":{"@id":"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#primaryimage"},"thumbnailUrl":"https:\/\/dhitelfon.com\/wp-content\/uploads\/2019\/05\/CAR-PLAY.jpg","datePublished":"2019-10-31T07:50:56+00:00","dateModified":"2019-10-31T07:50:56+00:00","author":{"@id":"https:\/\/dhitelfon.com\/#\/schema\/person\/a3af0a1b32d06c6e8f14a46114ea5509"},"description":"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona","breadcrumb":{"@id":"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#primaryimage","url":"https:\/\/dhitelfon.com\/wp-content\/uploads\/2019\/05\/CAR-PLAY.jpg","contentUrl":"https:\/\/dhitelfon.com\/wp-content\/uploads\/2019\/05\/CAR-PLAY.jpg","width":1633,"height":941,"caption":"Con este pincho USB se puede usar CarPlay en casi cualquier coche"},{"@type":"BreadcrumbList","@id":"https:\/\/dhitelfon.com\/te-explicamos-que-es-apple-carplay-y-como-funciona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dhitelfon.com\/"},{"@type":"ListItem","position":2,"name":"Te explicamos qu\u00e9 es Apple CarPlay y c\u00f3mo funciona"}]},{"@type":"WebSite","@id":"https:\/\/dhitelfon.com\/#website","url":"https:\/\/dhitelfon.com\/","name":"DHITELfon","description":"20 a\u00f1os de experiencia en el sector de comunicaciones, car audio, sistemas de seguridad para el autom\u00f3vil, sistemas de entretenimiento para el veh\u00edculo como tambi\u00e9n mayoristas de las mejores marcas. Centro instalador con taller propio","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dhitelfon.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/dhitelfon.com\/#\/schema\/person\/a3af0a1b32d06c6e8f14a46114ea5509","name":"Dhitelfon","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dhitelfon.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0107775308edc8de8d97206ddaa5c1bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0107775308edc8de8d97206ddaa5c1bb?s=96&d=mm&r=g","caption":"Dhitelfon"},"sameAs":["http:\/\/dhitelfon.com"],"url":"https:\/\/dhitelfon.com\/en\/author\/dhitelfon\/"}]}},"_links":{"self":[{"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/posts\/4039"}],"collection":[{"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/comments?post=4039"}],"version-history":[{"count":3,"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/posts\/4039\/revisions"}],"predecessor-version":[{"id":4042,"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/posts\/4039\/revisions\/4042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/media\/3941"}],"wp:attachment":[{"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/media?parent=4039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/categories?post=4039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dhitelfon.com\/en\/wp-json\/wp\/v2\/tags?post=4039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}